
{"id":5263,"date":"2022-11-04T10:48:48","date_gmt":"2022-11-04T09:48:48","guid":{"rendered":"https:\/\/unitusweb.azurewebsites.net\/laboratorio-di-microbiologia-generale-e-applicata\/"},"modified":"2025-01-13T12:45:50","modified_gmt":"2025-01-13T11:45:50","slug":"laboratorio-microbiologia-generale-applicata","status":"publish","type":"page","link":"https:\/\/www.unitus.it\/en\/departments\/dibaf\/research\/osservatori-dibaf\/laboratorio-microbiologia-generale-applicata\/","title":{"rendered":"Laboratorio di Microbiologia Generale e Applicata"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":15303,"menu_order":22,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"ppma_author":[73,95,109,189,221],"class_list":["post-5263","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Laboratorio di Microbiologia Generale e Applicata - Unitus<\/title>\n<meta name=\"description\" content=\"Consulta la pagina per maggiori informazioni riguardo al laboratorio di Microbiologia Generale e Applicata\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.unitus.it\/en\/departments\/dibaf\/research\/osservatori-dibaf\/laboratorio-microbiologia-generale-applicata\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Laboratorio di Microbiologia Generale e Applicata - Unitus\" \/>\n<meta property=\"og:description\" content=\"Consulta la pagina per maggiori informazioni riguardo al laboratorio di Microbiologia Generale e Applicata\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.unitus.it\/en\/departments\/dibaf\/research\/osservatori-dibaf\/laboratorio-microbiologia-generale-applicata\/\" \/>\n<meta property=\"og:site_name\" content=\"Unitus\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/universitadeglistudidellatuscia\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-13T11:45:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Laboratorio di Microbiologia Generale e Applicata - Unitus","description":"Consulta la pagina per maggiori informazioni riguardo al laboratorio di Microbiologia Generale e Applicata","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.unitus.it\/en\/departments\/dibaf\/research\/osservatori-dibaf\/laboratorio-microbiologia-generale-applicata\/","og_locale":"en_US","og_type":"article","og_title":"Laboratorio di Microbiologia Generale e Applicata - Unitus","og_description":"Consulta la pagina per maggiori informazioni riguardo al laboratorio di Microbiologia Generale e Applicata","og_url":"https:\/\/www.unitus.it\/en\/departments\/dibaf\/research\/osservatori-dibaf\/laboratorio-microbiologia-generale-applicata\/","og_site_name":"Unitus","article_publisher":"https:\/\/www.facebook.com\/universitadeglistudidellatuscia\/","article_modified_time":"2025-01-13T11:45:50+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.unitus.it\/en\/departments\/dibaf\/research\/osservatori-dibaf\/laboratorio-microbiologia-generale-applicata\/","url":"https:\/\/www.unitus.it\/en\/departments\/dibaf\/research\/osservatori-dibaf\/laboratorio-microbiologia-generale-applicata\/","name":"Laboratorio di Microbiologia Generale e Applicata - Unitus","isPartOf":{"@id":"https:\/\/www.unitus.it\/#website"},"datePublished":"2022-11-04T09:48:48+00:00","dateModified":"2025-01-13T11:45:50+00:00","description":"Consulta la pagina per maggiori informazioni riguardo al laboratorio di Microbiologia Generale e Applicata","breadcrumb":{"@id":"https:\/\/www.unitus.it\/en\/departments\/dibaf\/research\/osservatori-dibaf\/laboratorio-microbiologia-generale-applicata\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.unitus.it\/en\/departments\/dibaf\/research\/osservatori-dibaf\/laboratorio-microbiologia-generale-applicata\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.unitus.it\/en\/departments\/dibaf\/research\/osservatori-dibaf\/laboratorio-microbiologia-generale-applicata\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.unitus.it\/en\/"},{"@type":"ListItem","position":2,"name":"Departments","item":"https:\/\/www.unitus.it\/en\/departments\/"},{"@type":"ListItem","position":3,"name":"DIBAF","item":"https:\/\/www.unitus.it\/en\/departments\/dibaf\/"},{"@type":"ListItem","position":4,"name":"Research","item":"https:\/\/www.unitus.it\/en\/departments\/dibaf\/research\/"},{"@type":"ListItem","position":5,"name":"Observatories","item":"https:\/\/www.unitus.it\/en\/departments\/dibaf\/research\/osservatori-dibaf\/"},{"@type":"ListItem","position":6,"name":"Laboratorio di Microbiologia Generale e Applicata"}]},{"@type":"WebSite","@id":"https:\/\/www.unitus.it\/#website","url":"https:\/\/www.unitus.it\/","name":"Unitus","description":"","publisher":{"@id":"https:\/\/www.unitus.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.unitus.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.unitus.it\/#organization","name":"Universit\u00e0 degli Studi della Tuscia","alternateName":"Unitus","url":"https:\/\/www.unitus.it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.unitus.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.unitus.it\/wp-content\/uploads\/2022\/04\/unitus_marchio_2020_tagliato.png","contentUrl":"https:\/\/www.unitus.it\/wp-content\/uploads\/2022\/04\/unitus_marchio_2020_tagliato.png","width":1708,"height":660,"caption":"Universit\u00e0 degli Studi della Tuscia"},"image":{"@id":"https:\/\/www.unitus.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/universitadeglistudidellatuscia\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.unitus.it\/en\/wp-json\/wp\/v2\/pages\/5263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.unitus.it\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.unitus.it\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.unitus.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.unitus.it\/en\/wp-json\/wp\/v2\/comments?post=5263"}],"version-history":[{"count":1,"href":"https:\/\/www.unitus.it\/en\/wp-json\/wp\/v2\/pages\/5263\/revisions"}],"predecessor-version":[{"id":151013,"href":"https:\/\/www.unitus.it\/en\/wp-json\/wp\/v2\/pages\/5263\/revisions\/151013"}],"up":[{"embeddable":true,"href":"https:\/\/www.unitus.it\/en\/wp-json\/wp\/v2\/pages\/15303"}],"wp:attachment":[{"href":"https:\/\/www.unitus.it\/en\/wp-json\/wp\/v2\/media?parent=5263"}],"wp:term":[{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.unitus.it\/en\/wp-json\/wp\/v2\/ppma_author?post=5263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}